{"id":3,"date":"2023-10-08T10:38:29","date_gmt":"2023-10-08T10:38:29","guid":{"rendered":"https:\/\/certov.com\/wordpress\/?page_id=3"},"modified":"2023-12-02T17:08:54","modified_gmt":"2023-12-02T17:08:54","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/certov.com\/wordpress\/index.php\/privacy-policy\/","title":{"rendered":"Impressum &#038; Datenschutz"},"content":{"rendered":"\n<p>alle Rechte vorbehalten sowie f\u00fcr den Inhalt verantwortlich<\/p>\n\n\n\n<p>\u010certov Architects<\/p>\n\n\n\n<p>Architekt DI Ferdinand \u010certov<br>Staatl. befugter u. beeideter Ziviltechniker<\/p>\n\n\n\n<p>Gleisdorfergasse 11<br>8010 Graz<\/p>\n\n\n\n<p><strong>Datenschutzerkl\u00e4rung<\/strong><br>Der Schutz Ihrer pers\u00f6nlichen Daten ist uns ein besonderes Anliegen. Wir verarbeiten Ihre Daten daher ausschlie\u00dflich auf Grundlage der gesetzlichen Bestimmungen (DSGVO, TKG 2003). In diesen Datenschutzinformationen informieren wir Sie \u00fcber die wichtigsten Aspekte der Datenverarbeitung im Rahmen unserer Website.&nbsp;<br>Beim Besuch unserer Webseite wird Ihre IP-Adresse, Beginn und Ende der Sitzung f\u00fcr die Dauer dieser Sitzung erfasst. Dies ist technisch bedingt und stellt damit ein berechtigtes Interesse iSv Art 6 Abs 1 lit f DSGVO dar. Soweit im Folgenden nichts anderes geregelt wird, werden diese Daten von uns nicht weiterverarbeitet.<br><br><strong>Kontakt mit uns<\/strong><br>Wenn Sie mit uns Kontakt aufnehmen, werden Ihre angegebenen Daten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen sechs Monate bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.&nbsp;<br><br><strong>Cookies<\/strong><br>Unsere Website verwendet so genannte Cookies. Dabei handelt es sich um kleine Textdateien, die mit Hilfe des Browsers auf Ihrem Endger\u00e4t abgelegt werden. Sie richten keinen Schaden an.&nbsp;<br>Wir nutzen Cookies dazu, unser Angebot nutzerfreundlich zu gestalten. Einige Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese l\u00f6schen. Sie erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<br>Wenn Sie dies nicht w\u00fcnschen, so k\u00f6nnen Sie Ihren Browser so einrichten, dass er Sie \u00fcber das Setzen von Cookies informiert und Sie dies nur im Einzelfall erlauben.&nbsp;<br>Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t unserer Website eingeschr\u00e4nkt sein.<br><br><strong>Ihre Rechte<\/strong><br>Ihnen stehen bez\u00fcglich Ihrer bei uns gespeicherten Daten&nbsp;grunds\u00e4tzlich die Rechte auf Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung, Daten\u00fcbertragbarkeit, Widerruf und Widerspruch zu. Wenn Sie glauben, dass die Verarbeitung Ihrer Daten gegen das Datenschutzrecht verst\u00f6\u00dft oder Ihre datenschutzrechtlichen Anspr\u00fcche sonst in einer Weise verletzt worden sind, k\u00f6nnen Sie sich bei uns (architekt@certov.com) oder der Datenschutzbeh\u00f6rde beschweren.<\/p>\n\n\n\n<p>Quelle:\u00a0<a href=\"https:\/\/www.wko.at\/internetrecht\/datenschutzerklaerung-checkliste-infopflichten-dsgvo-tkg-we\">WKO<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>alle Rechte vorbehalten sowie f\u00fcr den Inhalt verantwortlich \u010certov Architects Architekt DI Ferdinand \u010certovStaatl. befugter u. beeideter Ziviltechniker Gleisdorfergasse 118010 Graz Datenschutzerkl\u00e4rungDer Schutz Ihrer pers\u00f6nlichen Daten ist uns ein besonderes Anliegen. Wir verarbeiten Ihre Daten daher ausschlie\u00dflich auf Grundlage der gesetzlichen Bestimmungen (DSGVO, TKG 2003). In diesen Datenschutzinformationen informieren wir Sie \u00fcber die wichtigsten Aspekte [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":2,"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":1671,"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions\/1671"}],"wp:attachment":[{"href":"https:\/\/certov.com\/wordpress\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}